{"id":3035,"date":"2026-08-17T15:30:07","date_gmt":"2026-08-17T15:30:07","guid":{"rendered":"https:\/\/lasederia.com.py\/?post_type=product&#038;p=3035"},"modified":"2026-08-17T15:30:07","modified_gmt":"2026-08-17T15:30:07","slug":"tul-bordado-celestine-con-pedreria","status":"publish","type":"product","link":"https:\/\/lasederia.com.py\/en\/product\/tul-bordado-celestine-con-pedreria\/","title":{"rendered":"Tul Bordado Celestine con Pedrer\u00eda"},"content":{"rendered":"<p>Tul Bordado Celestine con Pedrer\u00eda. D<span style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, 'Helvetica Neue', Arial, 'Noto Sans', sans-serif, 'Apple Color Emoji', 'Segoe UI Emoji', 'Segoe UI Symbol', 'Noto Color Emoji';\">elicado tul transparente con un elaborado dise\u00f1o floral en blanco, creando una composici\u00f3n rica en detalles y contrastes. Flores, hojas y peque\u00f1as ramificaciones se distribuyen sobre la superficie junto a amplias secciones de entramado geom\u00e9trico tipo panal, aportando un efecto visual distintivo y sofisticado.<\/span><\/p>\n<p class=\"isSelectedEnd\">El bordado incorpora aplicaciones de peque\u00f1as cuentas, perlas y elementos brillantes que realzan determinadas flores y hojas con sutiles destellos. La combinaci\u00f3n entre zonas de bordado m\u00e1s compacto, transparencias y estructuras abiertas genera profundidad y textura, mientras sus terminaciones florales ornamentadas aportan un acabado especialmente trabajado.<\/p>\n<p class=\"isSelectedEnd\">Su riqueza visual permite utilizarlo tanto como tejido protagonista en una prenda completa como para aprovechar sectores espec\u00edficos del dise\u00f1o en cuerpos, escotes, mangas o terminaciones decorativas.<\/p>\n<h3><\/h3>","protected":false},"excerpt":{"rendered":"<p>Tul Bordado Celestine con Pedrer\u00eda. Delicado tul transparente con un elaborado dise\u00f1o floral en blanco, creando una composici\u00f3n rica en detalles y contrastes. Flores, hojas y peque\u00f1as ramificaciones se distribuyen sobre la superficie junto a amplias secciones de entramado geom\u00e9trico tipo panal, aportando un efecto visual distintivo y sofisticado. El bordado incorpora aplicaciones de peque\u00f1as cuentas, perlas y elementos brillantes que realzan determinadas flores y hojas con sutiles destellos. La combinaci\u00f3n entre zonas de bordado m\u00e1s compacto, transparencias y estructuras abiertas genera profundidad y textura, mientras sus terminaciones florales ornamentadas aportan un acabado especialmente trabajado. Su riqueza visual permite utilizarlo tanto como tejido protagonista en una prenda completa como para aprovechar sectores espec\u00edficos del dise\u00f1o en cuerpos, escotes, mangas o terminaciones decorativas.<\/p>","protected":false},"featured_media":3036,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[30,19],"product_tag":[791,2603,933,2599,53,2086,789,898,2606,366,2209,895,75,2227,99,500,872,2082,2604,298,642,539,233,456,912,100,471,101,2487,2605,1978,483,2286,990,981],"class_list":{"0":"post-3035","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-tul-bordado-blanco","7":"product_cat-the-bridal-edit","8":"product_tag-alta-costura","9":"product_tag-aplicaciones-brillantes","10":"product_tag-beaded-tulle","11":"product_tag-bordado-blanco","12":"product_tag-bordado-floral","13":"product_tag-bordado-geometrico","14":"product_tag-bridal-fabric","15":"product_tag-bridal-tulle","16":"product_tag-celestine","17":"product_tag-diseno-floral","18":"product_tag-embellished-tulle","19":"product_tag-embroidered-tulle","20":"product_tag-encaje-floral","21":"product_tag-flores-bordadas","22":"product_tag-lentejuelas","23":"product_tag-pearl-embroidered-tulle","24":"product_tag-pedreria","25":"product_tag-perlas","26":"product_tag-tejido-floral","27":"product_tag-tela-elegante","28":"product_tag-tela-para-novia","29":"product_tag-tela-para-vestido-de-novia","30":"product_tag-tela-para-vestidos","31":"product_tag-tela-para-vestidos-de-fiesta","32":"product_tag-tul-blanco","33":"product_tag-tul-bordado","34":"product_tag-tul-bordado-blanco","35":"product_tag-tul-bordado-floral","36":"product_tag-tul-con-brillo","37":"product_tag-tul-con-diseno-panal","38":"product_tag-tul-con-pedreria","39":"product_tag-tul-con-perlas","40":"product_tag-tul-de-novia","41":"product_tag-tul-floral","42":"product_tag-tul-nude","44":"first","45":"instock","46":"shipping-taxable","47":"purchasable","48":"product-type-simple"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lasederia.com.py\/en\/wp-json\/wp\/v2\/product\/3035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasederia.com.py\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lasederia.com.py\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lasederia.com.py\/en\/wp-json\/wp\/v2\/comments?post=3035"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasederia.com.py\/en\/wp-json\/wp\/v2\/media\/3036"}],"wp:attachment":[{"href":"https:\/\/lasederia.com.py\/en\/wp-json\/wp\/v2\/media?parent=3035"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lasederia.com.py\/en\/wp-json\/wp\/v2\/product_brand?post=3035"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lasederia.com.py\/en\/wp-json\/wp\/v2\/product_cat?post=3035"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lasederia.com.py\/en\/wp-json\/wp\/v2\/product_tag?post=3035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}