{"id":2957,"date":"2026-08-03T19:28:38","date_gmt":"2026-08-03T19:28:38","guid":{"rendered":"https:\/\/lasederia.com.py\/?post_type=product&#038;p=2957"},"modified":"2026-08-03T19:28:38","modified_gmt":"2026-08-03T19:28:38","slug":"tul-bordado-jardin-de-marfil","status":"publish","type":"product","link":"https:\/\/lasederia.com.py\/en\/product\/tul-bordado-jardin-de-marfil\/","title":{"rendered":"Tul Bordado Jard\u00edn de Marfil"},"content":{"rendered":"<p>Tul Bordado Jard\u00edn de Marfil. C<span style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, 'Helvetica Neue', Arial, 'Noto Sans', sans-serif, 'Apple Color Emoji', 'Segoe UI Emoji', 'Segoe UI Symbol', 'Noto Color Emoji';\">omposici\u00f3n floral abundante, formada por flores de distintos tama\u00f1os, peque\u00f1os ramilletes, hojas y ramas que se distribuyen arm\u00f3nicamente sobre una delicada base de tul transparente. Su dise\u00f1o bot\u00e1nico combina una est\u00e9tica rom\u00e1ntica con un aire fresco y natural.<\/span><\/p>\n<p data-start=\"902\" data-end=\"1200\">El bordado blanco posee una cobertura intensa y una textura suavemente elevada, que destaca cada p\u00e9talo y detalle vegetal sobre la transparencia del fondo. La variedad de formas y escalas aporta profundidad al dise\u00f1o, mientras que la base liviana permite conservar una apariencia delicada y et\u00e9rea.<\/p>\n<p data-start=\"1202\" data-end=\"1485\">Puede utilizarse sobre bases blancas, marfil, nude o champagne para crear diferentes niveles de contraste y resaltar la riqueza de su dise\u00f1o floral.<\/p>\n<p class=\"\" data-start=\"1487\" data-end=\"2002\" data-is-last-node=\"\" data-is-only-node=\"\">","protected":false},"excerpt":{"rendered":"<p>Tul Bordado Jard\u00edn de Marfil. Composici\u00f3n floral abundante, formada por flores de distintos tama\u00f1os, peque\u00f1os ramilletes, hojas y ramas que se distribuyen arm\u00f3nicamente sobre una delicada base de tul transparente. Su dise\u00f1o bot\u00e1nico combina una est\u00e9tica rom\u00e1ntica con un aire fresco y natural. El bordado blanco posee una cobertura intensa y una textura suavemente elevada, que destaca cada p\u00e9talo y detalle vegetal sobre la transparencia del fondo. La variedad de formas y escalas aporta profundidad al dise\u00f1o, mientras que la base liviana permite conservar una apariencia delicada y et\u00e9rea. Puede utilizarse sobre bases blancas, marfil, nude o champagne para crear diferentes niveles de contraste y resaltar la riqueza de su dise\u00f1o floral.<\/p>","protected":false},"featured_media":2958,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[30,19],"product_tag":[53,898,2552,480,2227,2489,902,2532,270,477,1513,642,1511,539,456,315,2135,100,471,101,2332,2339,2211,2286,990,795],"class_list":{"0":"post-2957","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-tul-bordado-blanco","7":"product_cat-the-bridal-edit","8":"product_tag-bordado-floral","9":"product_tag-bridal-tulle","10":"product_tag-embroidered-mesh-fabric","11":"product_tag-floral-embroidered-tulle","12":"product_tag-flores-bordadas","13":"product_tag-ivory-embroidered-tulle","14":"product_tag-tela-bordada","15":"product_tag-tela-bordada-blanca","16":"product_tag-tela-botanica","17":"product_tag-tela-para-alta-costura","18":"product_tag-tela-para-mangas","19":"product_tag-tela-para-novia","20":"product_tag-tela-para-sobrefalda","21":"product_tag-tela-para-vestido-de-novia","22":"product_tag-tela-para-vestidos-de-fiesta","23":"product_tag-tela-romantica","24":"product_tag-tela-transparente","25":"product_tag-tul-bordado","26":"product_tag-tul-bordado-blanco","27":"product_tag-tul-bordado-floral","28":"product_tag-tul-con-flores","29":"product_tag-tul-con-relieve","30":"product_tag-tul-de-lujo","31":"product_tag-tul-de-novia","32":"product_tag-tul-floral","33":"product_tag-wedding-fabric","35":"first","36":"instock","37":"shipping-taxable","38":"purchasable","39":"product-type-simple"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lasederia.com.py\/en\/wp-json\/wp\/v2\/product\/2957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasederia.com.py\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lasederia.com.py\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lasederia.com.py\/en\/wp-json\/wp\/v2\/comments?post=2957"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasederia.com.py\/en\/wp-json\/wp\/v2\/media\/2958"}],"wp:attachment":[{"href":"https:\/\/lasederia.com.py\/en\/wp-json\/wp\/v2\/media?parent=2957"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lasederia.com.py\/en\/wp-json\/wp\/v2\/product_brand?post=2957"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lasederia.com.py\/en\/wp-json\/wp\/v2\/product_cat?post=2957"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lasederia.com.py\/en\/wp-json\/wp\/v2\/product_tag?post=2957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}