{"id":2914,"date":"2026-07-18T23:27:53","date_gmt":"2026-07-18T23:27:53","guid":{"rendered":"https:\/\/lasederia.com.py\/?post_type=product&#038;p=2914"},"modified":"2026-08-03T19:04:54","modified_gmt":"2026-08-03T19:04:54","slug":"randa-de-encaje-con-pedreria","status":"publish","type":"product","link":"https:\/\/lasederia.com.py\/en\/product\/randa-de-encaje-con-pedreria\/","title":{"rendered":"Randa de Encaje con Pedrer\u00eda"},"content":{"rendered":"<p>Randa de Encaje con Pedrer\u00eda. D<span style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, 'Helvetica Neue', Arial, 'Noto Sans', sans-serif, 'Apple Color Emoji', 'Segoe UI Emoji', 'Segoe UI Symbol', 'Noto Color Emoji';\">elicado dise\u00f1o floral de inspiraci\u00f3n rom\u00e1ntica, desarrollado sobre una fina base de red. Sus flores, hojas y motivos org\u00e1nicos se distribuyen de manera armoniosa, combinando sectores de mayor concentraci\u00f3n ornamental con \u00e1reas m\u00e1s transparentes que aportan ligereza y profundidad.<\/span><\/p>\n<p data-start=\"1003\" data-end=\"1313\">El encaje est\u00e1 enriquecido con peque\u00f1as aplicaciones de mostacillas, canutillos y lentejuelas transparentes, que generan destellos sutiles al entrar en contacto con la luz. Sus bordes festoneados con delicadas pesta\u00f1as completan el dise\u00f1o y aportan una terminaci\u00f3n elegante, refinada y de apariencia artesanal.<\/p>\n<p data-start=\"1315\" data-end=\"1615\">Con una medida de <strong data-start=\"1333\" data-end=\"1373\">35 cm de ancho por 3 metros de largo<\/strong>, es ideal para mangas, escotes, corseter\u00eda, velos, capas, faldas, aplicaciones y terminaciones de vestidos de novia o fiesta. Su tono marfil y su brillo delicado permiten incorporarla en dise\u00f1os sofisticados sin perder suavidad ni elegancia.<\/p>\n<h3 data-section-id=\"dxdfnf\" data-start=\"1617\" data-end=\"1633\">Presentaci\u00f3n<\/h3>\n<p data-start=\"1635\" data-end=\"1722\"><strong data-start=\"1635\" data-end=\"1645\">Ancho:<\/strong> 35 cm<br data-start=\"1651\" data-end=\"1654\" \/><strong data-start=\"1654\" data-end=\"1664\">Largo:<\/strong> 3 metros<\/p>","protected":false},"excerpt":{"rendered":"<p>Randa de Encaje con Pedrer\u00eda. Delicado dise\u00f1o floral de inspiraci\u00f3n rom\u00e1ntica, desarrollado sobre una fina base de red. Sus flores, hojas y motivos org\u00e1nicos se distribuyen de manera armoniosa, combinando sectores de mayor concentraci\u00f3n ornamental con \u00e1reas m\u00e1s transparentes que aportan ligereza y profundidad. El encaje est\u00e1 enriquecido con peque\u00f1as aplicaciones de mostacillas, canutillos y lentejuelas transparentes, que generan destellos sutiles al entrar en contacto con la luz. Sus bordes festoneados con delicadas pesta\u00f1as completan el dise\u00f1o y aportan una terminaci\u00f3n elegante, refinada y de apariencia artesanal. Con una medida de 35 cm de ancho por 3 metros de largo, es ideal para mangas, escotes, corseter\u00eda, velos, capas, faldas, aplicaciones y terminaciones de vestidos de novia o fiesta. Su tono marfil y su brillo delicado permiten incorporarla en dise\u00f1os sofisticados sin perder suavidad ni elegancia. Presentaci\u00f3n Ancho: 35 cmLargo: 3 metros<\/p>","protected":false},"featured_media":2915,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2525,19],"product_tag":[2523,632,2524,81,2521,1078,1080,2288,2287,2442,1522,75,1500,1083,2508,2507,2306,2506,88,2517,2444,2509,2519,2522,2520,2499,2501,2511,2503,639],"class_list":{"0":"post-2914","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-randas","7":"product_cat-the-bridal-edit","8":"product_tag-beaded-lace-trim","9":"product_tag-bridal-lace","10":"product_tag-embellished-lace","11":"product_tag-encaje-blanco","12":"product_tag-encaje-con-brillo","13":"product_tag-encaje-con-canutillos","14":"product_tag-encaje-con-lentejuelas","15":"product_tag-encaje-con-mostacillas","16":"product_tag-encaje-con-pedreria","17":"product_tag-encaje-con-pestanas","18":"product_tag-encaje-festoneado","19":"product_tag-encaje-floral","20":"product_tag-encaje-marfil","21":"product_tag-encaje-nupcial","22":"product_tag-encaje-para-alta-costura","23":"product_tag-encaje-para-mangas","24":"product_tag-encaje-para-novia","25":"product_tag-encaje-para-velos","26":"product_tag-encaje-para-vestidos","27":"product_tag-encaje-tipo-chantilly","28":"product_tag-eyelash-lace","29":"product_tag-ivory-lace-trim","30":"product_tag-randa-3-metros","31":"product_tag-randa-35-cm","32":"product_tag-randa-con-pedreria","33":"product_tag-randa-de-encaje","34":"product_tag-randa-marfil","35":"product_tag-scalloped-lace","36":"product_tag-tira-de-encaje","37":"product_tag-wedding-lace","39":"first","40":"instock","41":"shipping-taxable","42":"purchasable","43":"product-type-simple"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lasederia.com.py\/en\/wp-json\/wp\/v2\/product\/2914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasederia.com.py\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lasederia.com.py\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lasederia.com.py\/en\/wp-json\/wp\/v2\/comments?post=2914"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasederia.com.py\/en\/wp-json\/wp\/v2\/media\/2915"}],"wp:attachment":[{"href":"https:\/\/lasederia.com.py\/en\/wp-json\/wp\/v2\/media?parent=2914"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lasederia.com.py\/en\/wp-json\/wp\/v2\/product_brand?post=2914"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lasederia.com.py\/en\/wp-json\/wp\/v2\/product_cat?post=2914"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lasederia.com.py\/en\/wp-json\/wp\/v2\/product_tag?post=2914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}